{"id":5690,"date":"2019-10-15T15:26:49","date_gmt":"2019-10-15T15:26:49","guid":{"rendered":"https:\/\/www.doggiesdesign.hu\/?post_type=product&#038;p=5690"},"modified":"2022-07-31T23:21:33","modified_gmt":"2022-07-31T23:21:33","slug":"csontos-poraz","status":"publish","type":"product","link":"https:\/\/www.doggiesdesign.hu\/en\/shop\/kutya-poraz\/csontos-poraz\/","title":{"rendered":"Csontos p\u00f3r\u00e1z"},"content":{"rendered":"<h5 style=\"padding-left: 80px;\">2,5 cm sz\u00e9les<\/h5>\n<h5 style=\"padding-left: 80px;\">100% polipropil\u00e9n<\/h5>\n<h5 style=\"padding-left: 80px;\">puha tapint\u00e1s<\/h5>\n<h5 style=\"padding-left: 80px;\">strapab\u00edr\u00f3 anyag<\/h5>\n<h5 style=\"padding-left: 80px;\">30\u00b0C-on moshat\u00f3<\/h5>\n<h5 style=\"padding-left: 80px;\">k\u00e9zzel k\u00e9sz\u00edtett designer term\u00e9k<\/h5>\n","protected":false},"excerpt":{"rendered":"<h4>Csontos p\u00f3r\u00e1z k\u00e9sz\u00edt\u00e9s\u00e9n\u00e9l \u00fajragondoltuk a hagyom\u00e1nyosnak sz\u00e1m\u00edt\u00f3 csontos mint\u00e1t. Sz\u00ednei felt\u0171n\u0151ek \u00e9s harmonikusak.<\/h4>\n<h4>Lepd meg magadat \u00e9s kedvencedet egy \u00faj, min\u0151s\u00e9gi p\u00f3r\u00e1zzal \u00e9s \u00e9lvezz\u00e9tek k\u00f6z\u00f6sen a s\u00e9t\u00e1ltat\u00e1s apr\u00f3 \u00f6r\u00f6meit.<\/h4>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-9058\" src=\"https:\/\/www.doggiesdesign.hu\/wp-content\/uploads\/2020\/09\/Asset-7@2x.png\" alt=\"\" width=\"292\" height=\"138\" \/><\/p>\n","protected":false},"featured_media":6431,"comment_status":"open","ping_status":"closed","template":"","meta":{"_mi_skip_tracking":false},"product_cat":[310,29],"product_tag":[151,117,87,104,71,85,88],"translation":{"provider":"WPGlobus","version":"2.10.9","language":"en","enabled_languages":["hu","en"],"languages":{"hu":{"title":true,"content":true,"excerpt":true},"en":{"title":false,"content":false,"excerpt":false}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Csontos p\u00f3r\u00e1z - Doggies Design<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.doggiesdesign.hu\/shop\/kutya-poraz\/csontos-poraz\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Csontos p\u00f3r\u00e1z - Doggies Design\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.doggiesdesign.hu\/shop\/kutya-poraz\/csontos-poraz\/\" \/>\n<meta property=\"og:site_name\" content=\"Doggies Design\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/doggiesdesign\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-31T23:21:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.doggiesdesign.hu\/wp-content\/uploads\/2019\/10\/IMG_7698-scaled-e1602534539551.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.doggiesdesign.hu\/shop\/kutya-poraz\/csontos-poraz\/\",\"url\":\"https:\/\/www.doggiesdesign.hu\/shop\/kutya-poraz\/csontos-poraz\/\",\"name\":\"Csontos p\u00f3r\u00e1z - Doggies Design\",\"isPartOf\":{\"@id\":\"https:\/\/www.doggiesdesign.hu\/#website\"},\"datePublished\":\"2019-10-15T15:26:49+00:00\",\"dateModified\":\"2022-07-31T23:21:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.doggiesdesign.hu\/shop\/kutya-poraz\/csontos-poraz\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.doggiesdesign.hu\/shop\/kutya-poraz\/csontos-poraz\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.doggiesdesign.hu\/shop\/kutya-poraz\/csontos-poraz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.doggiesdesign.hu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.doggiesdesign.hu\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Csontos p\u00f3r\u00e1z\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.doggiesdesign.hu\/#website\",\"url\":\"https:\/\/www.doggiesdesign.hu\/\",\"name\":\"Doggies Design\",\"description\":\"A kuty&aacute;k st&iacute;lusa\",\"publisher\":{\"@id\":\"https:\/\/www.doggiesdesign.hu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.doggiesdesign.hu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.doggiesdesign.hu\/#organization\",\"name\":\"Doggies Design\",\"url\":\"https:\/\/www.doggiesdesign.hu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.doggiesdesign.hu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.doggiesdesign.hu\/wp-content\/uploads\/2022\/01\/cropped-Artboard-10@4x.png\",\"contentUrl\":\"https:\/\/www.doggiesdesign.hu\/wp-content\/uploads\/2022\/01\/cropped-Artboard-10@4x.png\",\"width\":254,\"height\":202,\"caption\":\"Doggies Design\"},\"image\":{\"@id\":\"https:\/\/www.doggiesdesign.hu\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/doggiesdesign\/\",\"https:\/\/www.facebook.com\/doggiesdesign\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Csontos p\u00f3r\u00e1z - Doggies Design","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.doggiesdesign.hu\/shop\/kutya-poraz\/csontos-poraz\/","og_locale":"en_US","og_type":"article","og_title":"Csontos p\u00f3r\u00e1z - Doggies Design","og_url":"https:\/\/www.doggiesdesign.hu\/shop\/kutya-poraz\/csontos-poraz\/","og_site_name":"Doggies Design","article_publisher":"https:\/\/www.facebook.com\/doggiesdesign\/","article_modified_time":"2022-07-31T23:21:33+00:00","og_image":[{"width":1920,"height":1920,"url":"https:\/\/www.doggiesdesign.hu\/wp-content\/uploads\/2019\/10\/IMG_7698-scaled-e1602534539551.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.doggiesdesign.hu\/shop\/kutya-poraz\/csontos-poraz\/","url":"https:\/\/www.doggiesdesign.hu\/shop\/kutya-poraz\/csontos-poraz\/","name":"Csontos p\u00f3r\u00e1z - Doggies Design","isPartOf":{"@id":"https:\/\/www.doggiesdesign.hu\/#website"},"datePublished":"2019-10-15T15:26:49+00:00","dateModified":"2022-07-31T23:21:33+00:00","breadcrumb":{"@id":"https:\/\/www.doggiesdesign.hu\/shop\/kutya-poraz\/csontos-poraz\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.doggiesdesign.hu\/shop\/kutya-poraz\/csontos-poraz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.doggiesdesign.hu\/shop\/kutya-poraz\/csontos-poraz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.doggiesdesign.hu\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.doggiesdesign.hu\/shop\/"},{"@type":"ListItem","position":3,"name":"Csontos p\u00f3r\u00e1z"}]},{"@type":"WebSite","@id":"https:\/\/www.doggiesdesign.hu\/#website","url":"https:\/\/www.doggiesdesign.hu\/","name":"Doggies Design","description":"A kuty&aacute;k st&iacute;lusa","publisher":{"@id":"https:\/\/www.doggiesdesign.hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.doggiesdesign.hu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.doggiesdesign.hu\/#organization","name":"Doggies Design","url":"https:\/\/www.doggiesdesign.hu\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.doggiesdesign.hu\/#\/schema\/logo\/image\/","url":"https:\/\/www.doggiesdesign.hu\/wp-content\/uploads\/2022\/01\/cropped-Artboard-10@4x.png","contentUrl":"https:\/\/www.doggiesdesign.hu\/wp-content\/uploads\/2022\/01\/cropped-Artboard-10@4x.png","width":254,"height":202,"caption":"Doggies Design"},"image":{"@id":"https:\/\/www.doggiesdesign.hu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/doggiesdesign\/","https:\/\/www.facebook.com\/doggiesdesign\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.doggiesdesign.hu\/en\/wp-json\/wp\/v2\/product\/5690"}],"collection":[{"href":"https:\/\/www.doggiesdesign.hu\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.doggiesdesign.hu\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.doggiesdesign.hu\/en\/wp-json\/wp\/v2\/comments?post=5690"}],"version-history":[{"count":2,"href":"https:\/\/www.doggiesdesign.hu\/en\/wp-json\/wp\/v2\/product\/5690\/revisions"}],"predecessor-version":[{"id":9133,"href":"https:\/\/www.doggiesdesign.hu\/en\/wp-json\/wp\/v2\/product\/5690\/revisions\/9133"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.doggiesdesign.hu\/en\/wp-json\/wp\/v2\/media\/6431"}],"wp:attachment":[{"href":"https:\/\/www.doggiesdesign.hu\/en\/wp-json\/wp\/v2\/media?parent=5690"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.doggiesdesign.hu\/en\/wp-json\/wp\/v2\/product_cat?post=5690"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.doggiesdesign.hu\/en\/wp-json\/wp\/v2\/product_tag?post=5690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}